{"id":3961,"date":"2025-12-29T17:00:00","date_gmt":"2025-12-30T00:00:00","guid":{"rendered":"https:\/\/trimira.com\/boardgames\/?page_id=3961"},"modified":"2025-12-29T17:00:00","modified_gmt":"2025-12-30T00:00:00","slug":"home-2","status":"publish","type":"page","link":"https:\/\/trimira.com\/boardgames\/","title":{"rendered":"Home"},"content":{"rendered":"<div id=\"pl-3961\"  class=\"panel-layout\" ><div id=\"pg-3961-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-3961-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-3961-0-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-45aad0572163-3961\"\n\t\t\t\n\t\t><div class=\"sow-headline-container \">\n\t\t\t\t\t\t\t<h1 class=\"sow-headline\">\n\t\t\t\t\t\tWelcome To TriMira Games\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/div>\n<\/div><\/div><div id=\"panel-3961-0-0-1\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p style=\"text-align: center;\">Below you'll find a catalog of original prototypes. Each board game I design has a simple goal: <em><strong>to make the familiar feel fresh again<\/strong>.<br \/>\n<\/em>That means starting with rarely used mechanics, blending them with familiar ones, and wrapping it all in themes that spark curiosity.<br \/>\nSome of the prototypes are ready to pitch, others still in development, but all are built to stand out.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-3961-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-3961-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-3961-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-medium wp-image-3334\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/alien_invasion_cover_2.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/alien_invasion_cover_2.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/alien_invasion_cover_2.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/alien_invasion_cover_2.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/alien_invasion_cover_2.png?w=967&amp;ssl=1 967w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-medium wp-image-3336\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/amazing_vowel_logo_2.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/amazing_vowel_logo_2.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/amazing_vowel_logo_2.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/amazing_vowel_logo_2.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/amazing_vowel_logo_2.png?w=967&amp;ssl=1 967w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-medium wp-image-3340\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/cover_art_prototype_3-1.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/cover_art_prototype_3-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/cover_art_prototype_3-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/cover_art_prototype_3-1.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/cover_art_prototype_3-1.png?w=967&amp;ssl=1 967w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3342\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/fibonacci_attack_cover_2.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/fibonacci_attack_cover_2.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/fibonacci_attack_cover_2.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/fibonacci_attack_cover_2.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/fibonacci_attack_cover_2.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3450\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Untitled.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Untitled.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Untitled.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Untitled.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Untitled.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3452\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hackers_blog_logo.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hackers_blog_logo.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hackers_blog_logo.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hackers_blog_logo.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hackers_blog_logo.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3455\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hexchange_blog_logo.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hexchange_blog_logo.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hexchange_blog_logo.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hexchange_blog_logo.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hexchange_blog_logo.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3456\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?w=1091&amp;ssl=1 1091w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3435\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/contradiction_engine_1.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/contradiction_engine_1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/contradiction_engine_1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/contradiction_engine_1.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/contradiction_engine_1.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3454\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hex_chain_blog_logo.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hex_chain_blog_logo.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hex_chain_blog_logo.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hex_chain_blog_logo.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hex_chain_blog_logo.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3666\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/nybrai_blog_graphic_v2.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/nybrai_blog_graphic_v2.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/nybrai_blog_graphic_v2.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/nybrai_blog_graphic_v2.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/nybrai_blog_graphic_v2.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3468\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/order_vs_chaos_blog_pic-1.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/order_vs_chaos_blog_pic-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/order_vs_chaos_blog_pic-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/order_vs_chaos_blog_pic-1.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/order_vs_chaos_blog_pic-1.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3465\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/perfect_balance_blog.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/perfect_balance_blog.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/perfect_balance_blog.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/perfect_balance_blog.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/perfect_balance_blog.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3463\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/salvage_wars_blog_pic.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/salvage_wars_blog_pic.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/salvage_wars_blog_pic.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/salvage_wars_blog_pic.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/salvage_wars_blog_pic.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3470\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/synkra_tech_blog_pic.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/synkra_tech_blog_pic.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/synkra_tech_blog_pic.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/synkra_tech_blog_pic.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/synkra_tech_blog_pic.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3344\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/free_trade_cover_3.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/free_trade_cover_3.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/free_trade_cover_3.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/free_trade_cover_3.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/free_trade_cover_3.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><img loading=\"lazy\" data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3472\" src=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/villain_inc_blog_pic.png?resize=100%2C100&#038;ssl=1\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/villain_inc_blog_pic.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/villain_inc_blog_pic.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/villain_inc_blog_pic.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/villain_inc_blog_pic.png?w=967&amp;ssl=1 967w\" sizes=\"auto, (max-width: 100px) 100vw, 100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-3961-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-3961-1-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h6 style=\"text-align: center;\">Explore the collection and reach out if something sparks your interest.<br \/>\n<a href=\"https:\/\/trimira.com\/boardgames\/about-me\/\">Click here to learn more about me and my design philosophy<\/a><\/h6>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3915-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"3915\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/boardgames\/wp-json\/wp\/v2\/pages\/3961#wpcf7-f3915-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3915\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3915-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> Name (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Email (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Message (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Submit\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"37\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-3961-2\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-3961-2\" data-stretch-type=\"full\" ><div id=\"pgc-3961-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-3961-2-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"panel-widget-style panel-widget-style-for-3961-2-0-0\" ><div id=\"pl-w68fa67cf36d5e\"  class=\"panel-layout\" ><div id=\"pg-w68fa67cf36d5e-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w68fa67cf36d5e-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/alien-invasion\/\">Alien Invasion<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-0-1\" class=\"so-panel widget widget_sow-image\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/alien-invasion\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/alien_invasion_cover_2.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/alien_invasion_cover_2.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/alien_invasion_cover_2.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/alien_invasion_cover_2.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/alien_invasion_cover_2.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-0-2\" class=\"so-panel widget widget_sow-image\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Development.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-0-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Alien Invasion<\/strong> is a 1-5 player cooperative strategy game where players fend off an evolving alien threat. Powered by a machine-learning mechanic, the game learns and adapts, growing smarter with every move. No two games are ever the same.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/en.wikipedia.org\/wiki\/Matchbox_Educable_Noughts_and_Crosses_Engine\">MENACE Inspired<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2664\/deck-bag-and-pool-building\">Deck Building \/ Destruction<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2849\/tech-trees-tech-tracks\">Tech Tree<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/alien-invasion\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-0-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"4\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/amazing-vowel-race\/\">Amazing Vowel Race<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-1-1\" class=\"so-panel widget widget_sow-image\" data-index=\"5\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/amazing-vowel-race\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/amazing_vowel_logo_2.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/amazing_vowel_logo_2.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/amazing_vowel_logo_2.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/amazing_vowel_logo_2.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/amazing_vowel_logo_2.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-1-2\" class=\"so-panel widget widget_sow-image\" data-index=\"6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?w=673&amp;ssl=1 673w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?resize=300%2C38&amp;ssl=1 300w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-1-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"7\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>The Amazing Vowel Race<\/strong> is a fast-paced strategy game where players predict the position of the racing vowels and control the race by playing pre-printed word cards. It's about timing, controlling, and outsmarting in a race where every word matters.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/3006\/predictive-bid\">Predictive Bid<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2958\/moving-multiple-units\">Moving Multiple Units<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2040\/hand-management\">Hand Management<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/amazing-vowel-race\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-0-2\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-0-2-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"8\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/destined-to-fail\/\">Destined To Fail<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-2-1\" class=\"so-panel widget widget_sow-image\" data-index=\"9\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/destined-to-fail\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/cover_art_prototype_3-1.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/cover_art_prototype_3-1.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/cover_art_prototype_3-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/cover_art_prototype_3-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/cover_art_prototype_3-1.png?resize=768%2C768&amp;ssl=1 768w\" title=\"cover_art_prototype_3\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-2-2\" class=\"so-panel widget widget_sow-image\" data-index=\"10\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?w=673&amp;ssl=1 673w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?resize=300%2C38&amp;ssl=1 300w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-2-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"11\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>In <strong>Destined To Fail<\/strong> players compete in a twisted trick-taking game where failure is not only an option... it's the goal. In this game coming in last (or even second place) is better than winning. Players carefully misplay tricks, manage their score, and try to stay one step behind.<\/p>\n<p><strong>Key Game Mechanics Used:<br \/>\n<\/strong><a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2821\/single-loser-game\">Single Loser Game<\/a><strong><br \/>\n<\/strong><a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2009\/trick-taking\">Trick-Taking<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2829\/turn-order-claim-action\">Turn Order: Claim Action<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/destined-to-fail\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-0-3\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-0-3-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"12\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/fibonacci-attack\/\">Fibonacci Attack<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-3-1\" class=\"so-panel widget widget_sow-image\" data-index=\"13\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/fibonacci-attack\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/fibonacci_attack_cover_2.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/fibonacci_attack_cover_2.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/fibonacci_attack_cover_2.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/fibonacci_attack_cover_2.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/fibonacci_attack_cover_2.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-3-2\" class=\"so-panel widget widget_sow-image\" data-index=\"14\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Development.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-0-3-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"15\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Fibonacci Attack<\/strong> is a cooperative game where players navigate a rondel-style command wheel to deploy defenses and launch attacks against waves of enemies. Each action must be carefully timed as sequence-based escalation punishes poor planning.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/en.wikipedia.org\/wiki\/Fibonacci_sequence\">Fibonacci Sequence Inspired<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2813\/rondel\">Rondel<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamefamily\/39912\/category-tower-defense\">Tower Defense<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/fibonacci-attack\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-w68fa67cf36d5e-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w68fa67cf36d5e-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"16\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/free-trade\/\">Friends Like These<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-0-1\" class=\"so-panel widget widget_sow-image\" data-index=\"17\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/free-trade\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Untitled.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Untitled.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Untitled.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Untitled.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Untitled.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-0-2\" class=\"so-panel widget widget_sow-image\" data-index=\"18\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Development.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-0-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"19\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Friends Like These<\/strong> is a competitive strategy game where the only way to win is to negotiate, trade, and cooperate. Players help each other to help themselves but must be careful; every deal made might push your opponent closer to victory.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2858\/prisoners-dilemma\">Prisoner's Dilemma<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2820\/semi-cooperative-game\">Semi-Cooperative Game<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2008\/trading\">Trading<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/free-trade\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-1-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"20\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/hackers-updates\/\">Hackers<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-1-1\" class=\"so-panel widget widget_sow-image\" data-index=\"21\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/hackers-updates\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hackers_blog_logo.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hackers_blog_logo.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hackers_blog_logo.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hackers_blog_logo.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hackers_blog_logo.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-1-2\" class=\"so-panel widget widget_sow-image\" data-index=\"22\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?w=673&amp;ssl=1 673w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?resize=300%2C38&amp;ssl=1 300w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-1-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"23\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Hackers<\/strong> is a Cyberpunk themed strategy game where players attack their opponent's firewall to take over their central core. Players do this by collecting blocks of code which can be used to attack their opponent or traded in for powerful hacker tools for future use.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2955\/mancala\">Mancala<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2686\/take-that\">Take That<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2828\/turn-order-progressive\">Turn Order: Progressive<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/hackers-updates\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-1-2\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-1-2-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"24\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/hexchanged\/\">HexChange<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-2-1\" class=\"so-panel widget widget_sow-image\" data-index=\"25\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/hexchanged\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hexchange_blog_logo.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hexchange_blog_logo.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hexchange_blog_logo.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hexchange_blog_logo.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hexchange_blog_logo.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-2-2\" class=\"so-panel widget widget_sow-image\" data-index=\"26\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?w=673&amp;ssl=1 673w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?resize=300%2C38&amp;ssl=1 300w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-2-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"27\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>HexChange<\/strong> is a market management game where players collect hex coins to fulfill lucrative contracts. How lucrative is based on how well the players can manipulate the market. The game board is made up of modular hex pieces that build a new board every game.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2955\/mancala\">Mancala<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2011\/modular-board\">Modular Board<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2914\/increase-value-of-unchosen-resources\">Increased Value of Unchosen Resources<\/a><\/p>\n<p><strong>Rules:<\/strong><br \/>\n<a href=\"https:\/\/drive.google.com\/file\/d\/1WTaSAQouqTB7MHLqZ7ZVoYZbk-gjdVdW\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\">HexChange Rules (Google Drive)<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/hexchanged\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-1-3\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-1-3-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"28\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/induction-my-dear\/\">Inferred<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-3-1\" class=\"so-panel widget widget_sow-image\" data-index=\"29\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/induction-my-dear\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?fit=1091%2C1091&amp;ssl=1\" width=\"1091\" height=\"1091\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?w=1091&amp;ssl=1 1091w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/inferred_blog_logo.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-3-2\" class=\"so-panel widget widget_sow-image\" data-index=\"30\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Play_Testing.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Play_Testing.png?w=673&amp;ssl=1 673w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Play_Testing.png?resize=300%2C38&amp;ssl=1 300w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-1-3-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"31\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Inferred<\/strong> is a competitive logic game where each player receives a unique hidden rule and races to crack everyone else's. Players observe their opponent's patterns, test theories, and hope to discover the hidden patterns before their pattern is deciphered.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/3003\/induction\">Induction<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2060\/pattern-recognition\">Pattern Recognition<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2048\/pattern-building\">Pattern Building<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/induction-my-dear\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-w68fa67cf36d5e-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w68fa67cf36d5e-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-2-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"32\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/contradiction-engine\/\">Ingenium<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-0-1\" class=\"so-panel widget widget_sow-image\" data-index=\"33\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/contradiction-engine\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/contradiction_engine_1.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/contradiction_engine_1.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/contradiction_engine_1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/contradiction_engine_1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/contradiction_engine_1.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-0-2\" class=\"so-panel widget widget_sow-image\" data-index=\"34\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Development.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-0-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"35\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Ingenium <\/strong><small>(in-JEE-nee-um)<\/small> is a competitive Steampunk themed card game where players use paradoxical logic to solve shared invention challenges. Players race to complete contraptions with clashing tools, wild combinations, and unconventional thinking.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/en.wikipedia.org\/wiki\/TRIZ\">TRIZ Inspired<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2912\/contracts\">Contracts<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2060\/pattern-recognition\">Pattern Recognition<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/contradiction-engine\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-2-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"36\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/lynkex\/\">Linkex<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-1-1\" class=\"so-panel widget widget_sow-image\" data-index=\"37\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/lynkex\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hex_chain_blog_logo.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hex_chain_blog_logo.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hex_chain_blog_logo.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hex_chain_blog_logo.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/hex_chain_blog_logo.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-1-2\" class=\"so-panel widget widget_sow-image\" data-index=\"38\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?w=673&amp;ssl=1 673w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?resize=300%2C38&amp;ssl=1 300w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-1-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"39\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Lynkex<\/strong> is a 2-player abstract strategy game where players connect colored discs while blocking their opponent's moves. Players must play 3 different colored discs, 2 on their side and 1 on their opponent's side (blocking that color from use).<\/p>\n<p><strong>Key Game Mechanics Used:<br \/>\n<\/strong><a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2883\/connections\">Connections<\/a><strong><br \/>\n<\/strong><a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2026\/hexagon-grid\">Hexagon Grid<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2048\/pattern-building\">Pattern Building<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/hex-chain-updates\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-2-2\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-2-2-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"40\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/nymbrai\/\">Nymbrai<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-2-1\" class=\"so-panel widget widget_sow-image\" data-index=\"41\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/nymbrai\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/nybrai_blog_graphic_v2.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/nybrai_blog_graphic_v2.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/nybrai_blog_graphic_v2.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/nybrai_blog_graphic_v2.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/nybrai_blog_graphic_v2.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-2-2\" class=\"so-panel widget widget_sow-image\" data-index=\"42\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Play_Testing.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Play_Testing.png?w=673&amp;ssl=1 673w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Play_Testing.png?resize=300%2C38&amp;ssl=1 300w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-2-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"43\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>In <strong>Nymbrai<\/strong>, players are mages inscribing powerful runes into their spellbooks using shared magical energy - guided each round by precise flicks and shifting patterns. Combine glyphs, obey ancient constraints, and race to build spells using nothing but cunning and dexterity.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2860\/flicking\">Flicking<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2999\/bingo\">Bingo<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2048\/pattern-building\">Pattern Building<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/nymbrai\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-2-3\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-2-3-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"44\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\">Order vs Chaos<\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-3-1\" class=\"so-panel widget widget_sow-image\" data-index=\"45\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/order_vs_chaos_blog_pic-1.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/order_vs_chaos_blog_pic-1.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/order_vs_chaos_blog_pic-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/order_vs_chaos_blog_pic-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/order_vs_chaos_blog_pic-1.png?resize=768%2C768&amp;ssl=1 768w\" title=\"order_vs_chaos_blog_pic\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-3-2\" class=\"so-panel widget widget_sow-image\" data-index=\"46\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?w=673&amp;ssl=1 673w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?resize=300%2C38&amp;ssl=1 300w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-2-3-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"47\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Order vs Chaos<\/strong> is a 2-player tetrominos tile placement game that asks the ultimate question: Is it better to be in control OR have your life dictated by randomness? One player plays Order and the other plays Chaos as they race to fulfill contracts or to call forth entropy.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2888\/tug-of-war\">Tug Of War<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2002\/tile-placement\">Tile Placement<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2015\/variable-player-powers\">Variable Player Powers<\/a><\/p>\n<p><strong>More Information<\/strong><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-w68fa67cf36d5e-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w68fa67cf36d5e-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-3-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"48\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/perfect-balance\/\">Perfect Balance<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-0-1\" class=\"so-panel widget widget_sow-image\" data-index=\"49\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/perfect-balance\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/perfect_balance_blog.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/perfect_balance_blog.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/perfect_balance_blog.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/perfect_balance_blog.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/perfect_balance_blog.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-0-2\" class=\"so-panel widget widget_sow-image\" data-index=\"50\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?w=673&amp;ssl=1 673w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?resize=300%2C38&amp;ssl=1 300w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-0-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"51\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Perfect Balance<\/strong> is a solo abstract strategy game where the player move pieces to the different sides of the board without going off the edge. Each move grows more complex as it can affect up to four other pieces, challenging the player to maintain control and balance.<\/p>\n<p><strong>Key Game Mechanics Used:<br \/>\n<\/strong><a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2958\/moving-multiple-units\">Moving Multiple Units<\/a><strong><br \/>\n<\/strong><a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2035\/roll-spin-and-move\">Roll \/ Spin and Move<\/a><strong><br \/>\n<\/strong><a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2819\/solo-solitaire-game\">Solo \/ Solitaire Game<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/perfect-balance\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-3-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-3-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"52\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/junkbot-wars-update\/\">Salvage Wars<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-1-1\" class=\"so-panel widget widget_sow-image\" data-index=\"53\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/junkbot-wars-update\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/salvage_wars_blog_pic.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/salvage_wars_blog_pic.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/salvage_wars_blog_pic.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/salvage_wars_blog_pic.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/salvage_wars_blog_pic.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-1-2\" class=\"so-panel widget widget_sow-image\" data-index=\"54\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Development.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-1-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"55\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>In <strong>Salvage Wars<\/strong> players race to scavenge scraps from a shared junkyard to build custom battle-bots to fight in the scrapyard arena. Players race to build their ultimate machine from discarded junk parts and face the ultimate challenge - Does their bot hold up or fall to pieces?<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2932\/auction-dutch-priority\">Auction: Dutch Priority<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2886\/king-of-the-hill\">King of the Hill<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2953\/programmed-movement\">Programmed Movement<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/junkbot-wars-update\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-3-2\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-3-2-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"56\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/synkra-tech\/\">Synkra-Tech<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-2-1\" class=\"so-panel widget widget_sow-image\" data-index=\"57\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/synkra-tech\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/synkra_tech_blog_pic.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/synkra_tech_blog_pic.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/synkra_tech_blog_pic.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/synkra_tech_blog_pic.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/synkra_tech_blog_pic.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-2-2\" class=\"so-panel widget widget_sow-image\" data-index=\"58\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Play_Testing.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Play_Testing.png?w=673&amp;ssl=1 673w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Play_Testing.png?resize=300%2C38&amp;ssl=1 300w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-2-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"59\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Synkra-Tech\u00a0<\/strong>is a competitive engine-building game where players design and optimize impulse-driven factory systems to fulfill custom product orders. Efficiency is key as players race to outbuild rivals and satisfy the demands of a high-pressure market.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2952\/impulse-movement\">Impulse Movement<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2906\/i-cut-you-choose\">I Cut, You Choose<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2849\/tech-trees-tech-tracks\">Tech Trees \/ Tech Tracks<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/synkra-tech\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-3-3\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-3-3-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"60\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/tipping-point\/\">Tipping Point<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-3-1\" class=\"so-panel widget widget_sow-image\" data-index=\"61\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/trimira.com\/boardgames\/tipping-point\/\"\n\t\t\t\t\t>\n\t\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/free_trade_cover_3.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/free_trade_cover_3.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/free_trade_cover_3.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/free_trade_cover_3.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/free_trade_cover_3.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-3-2\" class=\"so-panel widget widget_sow-image\" data-index=\"62\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Development.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-3-3-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"63\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Tipping Point<\/strong> is a darkly satirical strategy game where players are bitter political rivals dismantling global stability. Players juggle crises across multiple tug-of-war fronts and focus on one thing - seizing power. War is inevitable... just make sure you're ready when it comes.<\/p>\n<p><strong>Key Game Mechanics Used:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2888\/tug-of-war\">Tug Of War<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2847\/advantage-token\">Advantage Token<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2864\/force-commitment\">Force Commitment<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/tipping-point\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-w68fa67cf36d5e-4\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w68fa67cf36d5e-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-4-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"64\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/trimira.com\/boardgames\/villain-inc-updates\/\">Villain Inc.<\/a><\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-4-0-1\" class=\"so-panel widget widget_sow-image\" data-index=\"65\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/villain_inc_blog_pic.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/villain_inc_blog_pic.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/villain_inc_blog_pic.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/villain_inc_blog_pic.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/villain_inc_blog_pic.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-4-0-2\" class=\"so-panel widget widget_sow-image\" data-index=\"66\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?fit=673%2C85&amp;ssl=1\" width=\"673\" height=\"85\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?w=673&amp;ssl=1 673w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/Status_Ready.png?resize=300%2C38&amp;ssl=1 300w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-4-0-3\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"67\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Villain Inc.<\/strong> casts players as evil CEOs scheming for global domination by gaining influence, seizing key infrastructure, and unleashing loyal Supervillains from their secret labs. But watch out... a relentless Superhero is always on your tail.<\/p>\n<p><strong>Key Game Mechanics Used:<br \/>\n<\/strong><a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2837\/interrupts\">Interrupts<\/a><strong><br \/>\n<\/strong><a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2080\/area-majority-influence\">Area Majority \/ Influence<\/a><strong><br \/>\n<\/strong><a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2082\/worker-placement\">Worker Placement<\/a><\/p>\n<p><a href=\"https:\/\/trimira.com\/boardgames\/villain-inc-updates\/\"><strong>More Information<\/strong><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-4-1\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-w68fa67cf36d5e-4-2\"  class=\"panel-grid-cell panel-grid-cell-empty panel-grid-cell-mobile-last\" ><\/div><div id=\"pgc-w68fa67cf36d5e-4-3\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><div id=\"pg-w68fa67cf36d5e-5\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w68fa67cf36d5e-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-5-0-0\" class=\"so-panel widget widget_block panel-first-child\" data-index=\"68\" ><hr><\/div><div id=\"panel-w68fa67cf36d5e-5-0-1\" class=\"so-panel widget widget_sow-headline\" data-index=\"69\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-ec1eb4cebc48\"\n\t\t\t\n\t\t><div class=\"sow-headline-container \">\n\t\t\t\t\t\t\t<h2 class=\"sow-headline\">\n\t\t\t\t\t\tIdeas In Work\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"decoration\">\n\t\t\t\t\t\t<div class=\"decoration-inside\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-5-0-2\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"70\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p style=\"text-align: center;\">Below are collection of concepts in progress and future projects I\u2019m excited to develop further.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-w68fa67cf36d5e-6\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w68fa67cf36d5e-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-6-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"71\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\">Karma Inc.<\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-6-0-1\" class=\"so-panel widget widget_sow-image\" data-index=\"72\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/karma_inc_blog_graphic2.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/karma_inc_blog_graphic2.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/karma_inc_blog_graphic2.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/karma_inc_blog_graphic2.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/karma_inc_blog_graphic2.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-6-0-2\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"73\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Karma Inc. <\/strong>was the title of a short story I wrote and it's just too good of a name not to make into a game. I\u2019m playing with the idea of a shared-action track where one player\u2019s action along the track triggers actions for the other players. A variation off of Follow or maybe Rondel.<\/p>\n<p><strong>Planned Mechanics:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2843\/follow\">Follow (variation that other players are forced to play a different action)<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-6-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-6-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"74\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\">Lines of Succession<\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-6-1-1\" class=\"so-panel widget widget_sow-image\" data-index=\"75\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/lines_of_success_blog_pic2.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/lines_of_success_blog_pic2.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/lines_of_success_blog_pic2.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/lines_of_success_blog_pic2.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/lines_of_success_blog_pic2.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-6-1-2\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"76\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Lines Of Succession <\/strong>has players draw out territories on a map to build their kingdom. Combining Area Control and Card Drafting with Line Drawing with variations of having multiple lines going at once feels like a nice combo to explore.<\/p>\n<p><strong>Planned Mechanics:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2039\/line-drawing\">Crayon Rail System<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2080\/area-majority-influence\">Area Majority \/ Influence<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2984\/closed-drafting\">Closed Drafting<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-6-2\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-6-2-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"77\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\">Nullen<\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-6-2-1\" class=\"so-panel widget widget_sow-image\" data-index=\"78\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/nullen_blog_pic_2-1.png?fit=967%2C967&amp;ssl=1\" width=\"967\" height=\"967\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/nullen_blog_pic_2-1.png?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/nullen_blog_pic_2-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/nullen_blog_pic_2-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/04\/nullen_blog_pic_2-1.png?resize=768%2C768&amp;ssl=1 768w\" title=\"nullen_blog_pic_2\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-6-2-2\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"79\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Basic idea for <strong>Nullen <\/strong>is a dreamscape dungeon crawl like game. I would like to use a Roll \/ Spin and Move mechanic because it's looked down upon in the gaming community and I wanted to see if I could make a solid, fun, and strategically satisfying game with this mechanic.<\/p>\n<p><strong>Planned Mechanics:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2035\/roll-spin-and-move\">Roll \/ Spin and Move (variation where the dice are subtracted from each other)<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-6-3\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-6-3-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"80\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\">Soul Asset, Inc.<\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-6-3-1\" class=\"so-panel widget widget_sow-image\" data-index=\"81\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/Soul-Asset-Inc-Blog-Pic.png?fit=977%2C977&amp;ssl=1\" width=\"977\" height=\"977\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/Soul-Asset-Inc-Blog-Pic.png?w=977&amp;ssl=1 977w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/Soul-Asset-Inc-Blog-Pic.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/Soul-Asset-Inc-Blog-Pic.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/05\/Soul-Asset-Inc-Blog-Pic.png?resize=768%2C768&amp;ssl=1 768w\" title=\"Soul Asset Inc Blog Pic\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-6-3-2\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"82\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Soul Asset, Inc. <\/strong>has players play Demonic Law Interns crafting contracts so mortals can sell their souls. Due to several lawsuits these contracts must be designed correctly or there will be Hell to pay, literally.<\/p>\n<p><strong>Planned Mechanics:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2813\/rondel\">Rondel<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2912\/contracts\">Contracts<\/a><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2082\/worker-placement\">Worker Placement<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-w68fa67cf36d5e-7\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w68fa67cf36d5e-7-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w68fa67cf36d5e-7-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"83\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\">Studio Legends<\/h3>\n<\/div>\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-7-0-1\" class=\"so-panel widget widget_sow-image\" data-index=\"84\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" \n\tsrc=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/10\/studio_legends.png?fit=1024%2C1024&amp;ssl=1\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/10\/studio_legends.png?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/10\/studio_legends.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/10\/studio_legends.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/trimira.com\/boardgames\/wp-content\/uploads\/2025\/10\/studio_legends.png?resize=768%2C768&amp;ssl=1 768w\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-w68fa67cf36d5e-7-0-2\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"85\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Studio Legends <\/strong>is a Tug-of-War inspired concept where players have musician requirements (like fulfilling contracts) met by \"mixing\" the shared sound board. The idea is to have players being able to fulfill their requirements on any player's turn while they manipulate the sound board tug of war.<\/p>\n<p><strong>Planned Mechanics:<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/boardgamemechanic\/2888\/tug-of-war\">Tug Of War<\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-w68fa67cf36d5e-7-1\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-w68fa67cf36d5e-7-2\"  class=\"panel-grid-cell panel-grid-cell-empty panel-grid-cell-mobile-last\" ><\/div><div id=\"pgc-w68fa67cf36d5e-7-3\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Below you&#8217;ll find a catalog of original prototypes. Each board game I design has a simple goal: to make the familiar feel fresh again. That means starting with rarely used mechanics, blending them with familiar ones, and wrapping it all in themes that spark curiosity. Some of the prototypes are ready to pitch, others still [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"class_list":["post-3961","page","type-page","status-publish","hentry"],"blocksy_meta":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/trimira.com\/boardgames\/wp-json\/wp\/v2\/pages\/3961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trimira.com\/boardgames\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/trimira.com\/boardgames\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/trimira.com\/boardgames\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trimira.com\/boardgames\/wp-json\/wp\/v2\/comments?post=3961"}],"version-history":[{"count":2,"href":"https:\/\/trimira.com\/boardgames\/wp-json\/wp\/v2\/pages\/3961\/revisions"}],"predecessor-version":[{"id":3974,"href":"https:\/\/trimira.com\/boardgames\/wp-json\/wp\/v2\/pages\/3961\/revisions\/3974"}],"wp:attachment":[{"href":"https:\/\/trimira.com\/boardgames\/wp-json\/wp\/v2\/media?parent=3961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}